{"id":156,"count":2,"description":"","link":"https:\/\/haltia.com\/en\/category\/news-en-2\/","name":"news","slug":"news-en-2","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>news Archives - haltia.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/haltia.com\/en\/category\/news-en-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"news Archives - haltia.com\" \/>\n<meta property=\"og:url\" content=\"https:\/\/haltia.com\/en\/category\/news-en-2\/\" \/>\n<meta property=\"og:site_name\" content=\"haltia.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@HaltiaSuomi\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/haltia.com\\\/en\\\/category\\\/news-en-2\\\/\",\"url\":\"https:\\\/\\\/haltia.com\\\/en\\\/category\\\/news-en-2\\\/\",\"name\":\"news Archives - haltia.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/haltia.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/haltia.com\\\/en\\\/category\\\/news-en-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/haltia.com\\\/en\\\/category\\\/news-en-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/haltia.com\\\/en\\\/haltia-the-finnish-nature-and-outdoor-centre\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"news\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/haltia.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/haltia.com\\\/en\\\/\",\"name\":\"haltia.com\",\"description\":\"Ihan uusi WordPress-sivusto\",\"publisher\":{\"@id\":\"https:\\\/\\\/haltia.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/haltia.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/haltia.com\\\/en\\\/#organization\",\"name\":\"Haltia\",\"url\":\"https:\\\/\\\/haltia.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/haltia.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/haltia.com\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/haltia-logoweb.png\",\"contentUrl\":\"https:\\\/\\\/haltia.com\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/haltia-logoweb.png\",\"width\":550,\"height\":320,\"caption\":\"Haltia\"},\"image\":{\"@id\":\"https:\\\/\\\/haltia.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/haltiacom\",\"https:\\\/\\\/x.com\\\/HaltiaSuomi\",\"https:\\\/\\\/www.instagram.com\\\/haltiacom\\\/\",\"https:\\\/\\\/fi.wikipedia.org\\\/wiki\\\/Suomen_luontokeskus_Haltia\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"news Archives - haltia.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/haltia.com\/en\/category\/news-en-2\/","og_locale":"en_US","og_type":"article","og_title":"news Archives - haltia.com","og_url":"https:\/\/haltia.com\/en\/category\/news-en-2\/","og_site_name":"haltia.com","twitter_card":"summary_large_image","twitter_site":"@HaltiaSuomi","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/haltia.com\/en\/category\/news-en-2\/","url":"https:\/\/haltia.com\/en\/category\/news-en-2\/","name":"news Archives - haltia.com","isPartOf":{"@id":"https:\/\/haltia.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/haltia.com\/en\/category\/news-en-2\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/haltia.com\/en\/category\/news-en-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/haltia.com\/en\/haltia-the-finnish-nature-and-outdoor-centre\/"},{"@type":"ListItem","position":2,"name":"news"}]},{"@type":"WebSite","@id":"https:\/\/haltia.com\/en\/#website","url":"https:\/\/haltia.com\/en\/","name":"haltia.com","description":"Ihan uusi WordPress-sivusto","publisher":{"@id":"https:\/\/haltia.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/haltia.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/haltia.com\/en\/#organization","name":"Haltia","url":"https:\/\/haltia.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/haltia.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/haltia.com\/wp-content\/uploads\/2020\/06\/haltia-logoweb.png","contentUrl":"https:\/\/haltia.com\/wp-content\/uploads\/2020\/06\/haltia-logoweb.png","width":550,"height":320,"caption":"Haltia"},"image":{"@id":"https:\/\/haltia.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/haltiacom","https:\/\/x.com\/HaltiaSuomi","https:\/\/www.instagram.com\/haltiacom\/","https:\/\/fi.wikipedia.org\/wiki\/Suomen_luontokeskus_Haltia"]}]}},"_links":{"self":[{"href":"https:\/\/haltia.com\/en\/wp-json\/wp\/v2\/categories\/156","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/haltia.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/haltia.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/haltia.com\/en\/wp-json\/wp\/v2\/posts?categories=156"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}